{"id":2931,"date":"2023-04-05T11:29:43","date_gmt":"2023-04-05T11:29:43","guid":{"rendered":"https:\/\/empirecustomwindows.com\/?page_id=2931"},"modified":"2023-04-21T09:19:48","modified_gmt":"2023-04-21T09:19:48","slug":"roller-shades","status":"publish","type":"page","link":"https:\/\/empirecustomwindows.com\/es_mx\/portafolio\/cortinas-enrollables\/","title":{"rendered":"cortinas enrollables"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2931\" class=\"elementor elementor-2931\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fce6523 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"fce6523\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-778a201\" data-id=\"778a201\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b036c67 elementor-widget elementor-widget-heading\" data-id=\"b036c67\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">CORTINAS ENROLLABLES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e90b26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e90b26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4515a78\" data-id=\"4515a78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b2ff42 imges_1 elementor-widget elementor-widget-image\" data-id=\"1b2ff42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"404\" src=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg\" class=\"attachment-large size-large wp-image-2946\" alt=\"\" srcset=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg 840w, https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1-300x151.jpg 300w, https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1-768x388.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-acbc87e\" data-id=\"acbc87e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a216ae2 elementor-widget elementor-widget-heading\" data-id=\"a216ae2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CORTINAS ENROLLABLES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690faac elementor-widget elementor-widget-text-editor\" data-id=\"690faac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Nuestra exclusiva colecci\u00f3n de cortinas enrollables es elegante, minimalista y moderna. Hechas a mano seg\u00fan sus especificaciones exactas utilizando solo los mejores materiales ecol\u00f3gicos disponibles, las cortinas enrollables est\u00e1n disponibles tanto en materiales de filtrado de luz como de oscurecimiento. Las cortinas enrollables son una de las opciones m\u00e1s sencillas para cubrir ventanas. No solo ofrecen un estilo moderno y minimalista, sino que tambi\u00e9n son muy f\u00e1ciles de subir o bajar. Las cortinas enrollables est\u00e1n fabricadas con nuestro sistema premium de control de bucle continuo: una cadena de cuentas plateadas que le permite subir y bajar la cortina con facilidad y precisi\u00f3n. Podr\u00e1s disfrutar de la practicidad de las cortinas enrollables sin tener que sacrificar el estilo. Con opciones decorativas como cenefas, cornisas y vieiras, cada ventana de su hogar puede ser una forma de expresi\u00f3n creativa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0450af elementor-widget__width-initial c_button elementor-widget elementor-widget-button\" data-id=\"b0450af\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/empirecustomwindows.com\/es_mx\/contactenos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reservar ahora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e92c7ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e92c7ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6de415c\" data-id=\"6de415c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7759279 elementor-widget elementor-widget-heading\" data-id=\"7759279\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BENEFICIOS DE LAS CORTINAS ENROLLABLES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-771b45b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"771b45b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bc80f0d\" data-id=\"bc80f0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab42e29 elementor-widget elementor-widget-text-editor\" data-id=\"ab42e29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Lo minimalista est\u00e1 de moda tanto entre los propietarios como entre los decoradores. Y en un lugar como la ciudad de Nueva York, las decoraciones simples pueden equilibrar elegantemente el ajetreo de la vida urbana. En contraste con los patrones y l\u00edneas intensos, una persiana desplegable sencilla y elegante puede ser justo lo que necesita para perfeccionar una habitaci\u00f3n.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-44524f6\" data-id=\"44524f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e81e21 elementor-widget elementor-widget-text-editor\" data-id=\"9e81e21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Una opci\u00f3n confiable Nuestras cortinas enrollables se consideran una opci\u00f3n confiable ya que son decorativas y funcionales al mismo tiempo. Adem\u00e1s de la gracia y elegancia que muestran, tambi\u00e9n ayudan a proteger los muebles de interior. Se sabe que los fuertes rayos del sol tienen un efecto adverso en los muebles de interior y nuestras cortinas enrollables ayudan a controlarlos. . . .<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-00a8f68\" data-id=\"00a8f68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66651d7 elementor-widget elementor-widget-text-editor\" data-id=\"66651d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Menos contaminaci\u00f3n lum\u00ednica Las cortinas enrollables son algunas de las m\u00e1s efectivas para controlar la luz. Pueden estar hechos de materiales opacos para cortar completamente la luz en una habitaci\u00f3n en particular. Eso puede transformar un dormitorio en un refugio perfecto, eliminando la contaminaci\u00f3n lum\u00ednica del exterior. La Fundaci\u00f3n Nacional del Sue\u00f1o dice que es artificial. . .\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d5b015b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5b015b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e6f5eeb\" data-id=\"e6f5eeb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f17667 elementor-widget elementor-widget-text-editor\" data-id=\"0f17667\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Privacidad Si est\u00e1 cansado de las miradas no deseadas de los molestos vecinos a trav\u00e9s de sus ventanas, las cortinas enrollables de Empire Custom Windows pueden resultar ser los mejores tratamientos para ventanas para usted. Pueden bloquear completamente las vistas desde el exterior sin oscurecer el interior. Por lo tanto, no es necesario depender completamente de la iluminaci\u00f3n interior.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ff2e0e2\" data-id=\"ff2e0e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9dbc3ad elementor-widget elementor-widget-text-editor\" data-id=\"9dbc3ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sin carga para su bolsillo The Blinds Side es un nombre reputado por las persianas, cortinas y contraventanas de primera calidad que se pueden comprar a precios asequibles. Nos esforzamos por brindar la mejor experiencia a nuestros clientes. Por lo tanto, las cortinas enrollables que ofrecemos tienen un precio nominal. Por lo tanto. . .\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-455f3c4\" data-id=\"455f3c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5579631 elementor-widget elementor-widget-text-editor\" data-id=\"5579631\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ofrecemos una amplia gama de cortinas enrollables que se pueden instalar en cualquier entorno. Ya sea que est\u00e9 buscando cortinas para instalar en su oficina o en su hogar, puede contactarnos y obtener las cortinas enrollables m\u00e1s confiables y duraderas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5558fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5558fa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-943f47e\" data-id=\"943f47e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f146498 elementor-widget elementor-widget-heading\" data-id=\"f146498\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Complete este formulario y obtenga un presupuesto GRATIS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fff430b elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"fff430b\" data-element_type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;25&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.22.0 - 24-06-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button .elementor-button-content-wrapper{align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-form .elementor-button .elementor-button-content-wrapper{gap:5px}.elementor-form .elementor-button .elementor-button-icon,.elementor-form .elementor-button .elementor-button-text{flex-grow:unset;order:unset}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2931\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"fff430b\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Empire Custom Windows\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre completo\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Escriba su nombre\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCorreo electr\u00f3nico\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Escribe tu correo electr\u00f3nico\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTel\u00e9fono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Escribe tu n\u00famero de tel\u00e9fono\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"S\u00f3lo se aceptan n\u00fameros y caracteres telef\u00f3nicos (#, -, *, etc.).\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_c6497b7 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_c6497b7\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tC\u00f3digo postal\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_c6497b7]\" id=\"form-field-field_c6497b7\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Escribe tu c\u00f3digo postal\" required=\"required\" aria-required=\"true\" min=\"\" max=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_c0f0ff0 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_c0f0ff0\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tServicio requerido\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[field_c0f0ff0]\" id=\"form-field-field_c0f0ff0\" rows=\"4\" required=\"required\" aria-required=\"true\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-25 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenga un presupuesto gratuito<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"es_mx\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b29ee50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b29ee50\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87942e4\" data-id=\"87942e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6536023 elementor-widget elementor-widget-heading\" data-id=\"6536023\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OTRAS CORTINAS, PERSIANAS Y CORTINAS ENROLLABLES OFRECIDAS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9019a79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9019a79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7f55590\" data-id=\"7f55590\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-daa62e8 elementor-widget elementor-widget-heading\" data-id=\"daa62e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">  Persianas enrollables<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-14f024c\" data-id=\"14f024c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bb363e elementor-widget elementor-widget-heading\" data-id=\"2bb363e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persianas enrollables opacas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-465ca3b\" data-id=\"465ca3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32aeb98 elementor-widget elementor-widget-heading\" data-id=\"32aeb98\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">   Estores Enrollables A Medida<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-46f92e3\" data-id=\"46f92e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5b157d elementor-widget elementor-widget-heading\" data-id=\"c5b157d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Persianas enrollables transparentes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5930553 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5930553\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fa4e6cf\" data-id=\"fa4e6cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f0a0bb elementor-widget elementor-widget-heading\" data-id=\"7f0a0bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cortinas enrollables para exteriores<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5b08cdb\" data-id=\"5b08cdb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56e602e elementor-widget elementor-widget-heading\" data-id=\"56e602e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">  Persianas enrollables de bamb\u00fa<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d4fe19b\" data-id=\"d4fe19b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-519c4bf elementor-widget elementor-widget-heading\" data-id=\"519c4bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cortinas enrollables de tela<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-25f67de\" data-id=\"25f67de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74c0e40 elementor-widget elementor-widget-heading\" data-id=\"74c0e40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persianas enrollables motorizadas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da16a48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da16a48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-622d28a\" data-id=\"622d28a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0c5e4d elementor-widget elementor-widget-heading\" data-id=\"d0c5e4d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persianas enrollables t\u00e9rmicas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-148f954\" data-id=\"148f954\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adc3fad elementor-widget elementor-widget-heading\" data-id=\"adc3fad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cortinas Enrollables<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-40d761f\" data-id=\"40d761f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a41e149 elementor-widget elementor-widget-heading\" data-id=\"a41e149\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persianas Enrollables Inal\u00e1mbricas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4baba55\" data-id=\"4baba55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e1668c elementor-widget elementor-widget-heading\" data-id=\"8e1668c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persianas enrollables de madera<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de0574c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de0574c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a39075a\" data-id=\"a39075a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a50abc1 elementor-widget elementor-widget-heading\" data-id=\"a50abc1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00c1S PERSIANAS Y CORTINAS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3639ede elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3639ede\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a00b29e col-trangle\" data-id=\"a00b29e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f2b711 elementor-widget elementor-widget-image\" data-id=\"1f2b711\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"380\" height=\"254\" src=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-3-28-380x254-1.jpg\" class=\"attachment-large size-large wp-image-665\" alt=\"\" srcset=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-3-28-380x254-1.jpg 380w, https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-3-28-380x254-1-300x201.jpg 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-adbda02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adbda02\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ce6eb0f\" data-id=\"ce6eb0f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c323e94 elementor-widget elementor-widget-heading\" data-id=\"c323e94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CORTINAS TRANSPARENTES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b440997 elementor-widget elementor-widget-text-editor\" data-id=\"b440997\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>DISE\u00d1O \u2013 INTERIORES<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d3befd4 col-trangle\" data-id=\"d3befd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a8f84f elementor-widget elementor-widget-image\" data-id=\"1a8f84f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"380\" height=\"254\" src=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-2-24-380x254-1.jpg\" class=\"attachment-large size-large wp-image-686\" alt=\"\" srcset=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-2-24-380x254-1.jpg 380w, https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-2-24-380x254-1-300x201.jpg 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48ab830 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48ab830\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b1e1edc\" data-id=\"b1e1edc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3239a19 elementor-widget elementor-widget-heading\" data-id=\"3239a19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CORTINAS QUE OSCURECEN LA HABITACI\u00d3N<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c6a651 elementor-widget elementor-widget-text-editor\" data-id=\"0c6a651\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>DISE\u00d1O \u2013 INTERIORES<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6a5424a col-trangle\" data-id=\"6a5424a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffcf0d3 elementor-widget elementor-widget-image\" data-id=\"ffcf0d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"254\" src=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-4-18-380x254-1.jpg\" class=\"attachment-large size-large wp-image-687\" alt=\"\" srcset=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-4-18-380x254-1.jpg 380w, https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/Image-4-18-380x254-1-300x201.jpg 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82b3582 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82b3582\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3812248\" data-id=\"3812248\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b172fa elementor-widget elementor-widget-heading\" data-id=\"6b172fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CORTINAS TRANSPARENTES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65022a6 elementor-widget elementor-widget-text-editor\" data-id=\"65022a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>DISE\u00d1O \u2013 INTERIORES<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-42f441b col-trangle\" data-id=\"42f441b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2297ff elementor-widget elementor-widget-image\" data-id=\"c2297ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"254\" src=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/IMAGE-2-18-380x254-1.jpg\" class=\"attachment-large size-large wp-image-688\" alt=\"\" srcset=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/IMAGE-2-18-380x254-1.jpg 380w, https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/IMAGE-2-18-380x254-1-300x201.jpg 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-babe727 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"babe727\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b8c7038\" data-id=\"b8c7038\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97dad72 elementor-widget elementor-widget-heading\" data-id=\"97dad72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persianas opacas comerciales<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13668c7 elementor-widget elementor-widget-text-editor\" data-id=\"13668c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>DISE\u00d1O \u2013 INTERIORES<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ROLLER SHADES ROLLER SHADES Our exclusive Roller shades collection is sleek, minimal and modern. Handmade to your exact specifications using only the finest, eco-friendly materials available, the Roller Shades are available in both light filtering and blackout materials. Roller shades\u00a0are one of the simplest options for window coverage. Not only do they offer a modern, [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"parent":5349,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"two_page_speed":[],"footnotes":""},"class_list":["post-2931","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roller shades - Empire Custom Windows<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/empirecustomwindows.com\/es_mx\/portafolio\/cortinas-enrollables\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roller shades - Empire Custom Windows\" \/>\n<meta property=\"og:description\" content=\"ROLLER SHADES ROLLER SHADES Our exclusive Roller shades collection is sleek, minimal and modern. Handmade to your exact specifications using only the finest, eco-friendly materials available, the Roller Shades are available in both light filtering and blackout materials. Roller shades\u00a0are one of the simplest options for window coverage. Not only do they offer a modern, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/empirecustomwindows.com\/es_mx\/portafolio\/cortinas-enrollables\/\" \/>\n<meta property=\"og:site_name\" content=\"Empire Custom Windows\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/empirecustomwindows\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roller shades - Empire Custom Windows","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/empirecustomwindows.com\/es_mx\/portafolio\/cortinas-enrollables\/","og_locale":"es_MX","og_type":"article","og_title":"Roller shades - Empire Custom Windows","og_description":"ROLLER SHADES ROLLER SHADES Our exclusive Roller shades collection is sleek, minimal and modern. Handmade to your exact specifications using only the finest, eco-friendly materials available, the Roller Shades are available in both light filtering and blackout materials. Roller shades\u00a0are one of the simplest options for window coverage. Not only do they offer a modern, [&hellip;]","og_url":"https:\/\/empirecustomwindows.com\/es_mx\/portafolio\/cortinas-enrollables\/","og_site_name":"Empire Custom Windows","article_publisher":"https:\/\/www.facebook.com\/empirecustomwindows\/","og_image":[{"url":"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/","url":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/","name":"Roller shades - Empire Custom Windows","isPartOf":{"@id":"https:\/\/empirecustomwindows.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/#primaryimage"},"image":{"@id":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/#primaryimage"},"thumbnailUrl":"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg","datePublished":"2023-04-05T11:29:43+00:00","dateModified":"2023-04-21T09:19:48+00:00","breadcrumb":{"@id":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/#primaryimage","url":"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg","contentUrl":"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/1-840x424-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/empirecustomwindows.com\/portfolio\/roller-shades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/empirecustomwindows.com\/"},{"@type":"ListItem","position":2,"name":"portfolio","item":"https:\/\/empirecustomwindows.com\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Roller shades"}]},{"@type":"WebSite","@id":"https:\/\/empirecustomwindows.com\/#website","url":"https:\/\/empirecustomwindows.com\/","name":"Empire Custom Windows","description":"","publisher":{"@id":"https:\/\/empirecustomwindows.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/empirecustomwindows.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/empirecustomwindows.com\/#organization","name":"Empire Custom Windows","url":"https:\/\/empirecustomwindows.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empirecustomwindows.com\/#\/schema\/logo\/image\/","url":"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/newhighlightlogo.png","contentUrl":"https:\/\/empirecustomwindows.com\/wp-content\/uploads\/2023\/04\/newhighlightlogo.png","width":200,"height":60,"caption":"Empire Custom Windows"},"image":{"@id":"https:\/\/empirecustomwindows.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/empirecustomwindows\/","https:\/\/www.yelp.com\/biz\/empire-custom-windows-new-york-2"]}]}},"_links":{"self":[{"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/pages\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/comments?post=2931"}],"version-history":[{"count":62,"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/pages\/2931\/revisions"}],"predecessor-version":[{"id":5599,"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/pages\/2931\/revisions\/5599"}],"up":[{"embeddable":true,"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/pages\/5349"}],"wp:attachment":[{"href":"https:\/\/empirecustomwindows.com\/es_mx\/wp-json\/wp\/v2\/media?parent=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}